{"id":2247,"date":"2024-08-02T13:06:11","date_gmt":"2024-08-02T11:06:11","guid":{"rendered":"https:\/\/domingopintor.com\/?page_id=2247"},"modified":"2024-08-02T23:59:48","modified_gmt":"2024-08-02T21:59:48","slug":"politicadecookies","status":"publish","type":"page","link":"https:\/\/domingopintor.com\/es\/politicadecookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2247\" class=\"elementor elementor-2247\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9dc7f51 e-flex e-con-boxed e-con e-parent\" data-id=\"9dc7f51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0470d20 elementor-widget elementor-widget-spacer\" data-id=\"0470d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e65dad5 e-flex e-con-boxed e-con e-parent\" data-id=\"e65dad5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09d32a1 elementor-widget elementor-widget-heading\" data-id=\"09d32a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Cookies<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1914ec9 elementor-widget elementor-widget-text-editor\" data-id=\"1914ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00daltima modificaci\u00f3n: 2 de agosto de 2024.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c419fa elementor-widget elementor-widget-text-editor\" data-id=\"0c419fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Despu\u00e9s de una auditor\u00eda realizada por la informaci\u00f3n sobre las cookies que se utilizan en esta web, le informamos:<\/p><p>La Ley 34\/2002, de 11 de julio, de servicios de la sociedad de la informaci\u00f3n y de comercio electr\u00f3nico (LSSI-CE), obliga a todos aquellos que tienen un blog o una web a advertir al usuario del existencia de cookies, informar sobre ellas y solicitarle permiso para descargarlas.<\/p><p>Asimismo, tal y como dispone el art\u00edculo 22.2 de la Ley 34\/2002: \u201cLos prestadores de servicios podr\u00e1n utilizar dispositivos de almacenamiento y recuperaci\u00f3n de datos en equipos terminales de los destinatarios, siempre que los mismos hayan dado su consentimiento despu\u00e9s de que se les haya facilitado informaci\u00f3n clara y completa sobre su utilizaci\u00f3n, en particular, sobre los fines del tratamiento de los datos, de acuerdo con lo dispuesto en la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal\u201d.<\/p><p>Como responsable de esta web, y en cumplimiento del art\u00edculo mencionado anteriormente en lo referente a las cookies y teniendo en cuenta la forma en que funciona Internet y los sitios web, no siempre es posible contar con informaci\u00f3n actualizada de las cookies que terceras partes puedan utilizarse a trav\u00e9s de este sitio web.<\/p><p>Esto se aplica especialmente a casos en los que esta p\u00e1gina web contiene elementos integrados: es decir, textos, documentos, im\u00e1genes o breves pel\u00edculas que pueden almacenarse en otra parte, pero se muestran en nuestro sitio web.<\/p><p>Por tanto, si se encuentra con este tipo de cookies en este sitio web y no est\u00e1n enumeradas en la lista siguiente, le rogamos que nos lo comunique. Tambi\u00e9n puede ponerse en contacto directamente con el tercero para pedirle informaci\u00f3n sobre las cookies que coloca, la finalidad y la duraci\u00f3n de la cookie, y c\u00f3mo ha garantizado su privacidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3132e92 elementor-widget elementor-widget-heading\" data-id=\"3132e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 son las cookies?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-280816d elementor-widget elementor-widget-text-editor\" data-id=\"280816d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las cookies constituyen una herramienta utilizada por los servidores web para almacenar y recuperar informaci\u00f3n sobre sus visitantes. No es m\u00e1s que un archivo de texto que algunos servidores piden a nuestro navegador que escriba en nuestro disco duro, con informaci\u00f3n sobre lo que hemos estado haciendo por sus p\u00e1ginas. Poseen una fecha de caducidad, que puede oscilar desde el tiempo que dure la sesi\u00f3n hasta una fecha futura especificada, a partir de la cual dejan de ser operativas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d092d5 elementor-widget elementor-widget-heading\" data-id=\"5d092d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">1. Cookies que utiliza esta web<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9dd644 elementor-widget elementor-widget-text-editor\" data-id=\"d9dd644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En esta web se utilizan cookies de terceros para mejorar su experiencia de navegaci\u00f3n, ofrecer anuncios o contenido personalizados y analizar nuestro tr\u00e1fico.<\/p><p>Las cookies utilizadas en <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a> se asocian \u00fanicamente con un usuario an\u00f3nimo y su ordenador, no proporcionan referencias que permitan deducir el nombre y apellidos del usuario y no pueden leer datos de su disco duro ni incluir virus en sus textos. Asimismo, <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a> no puede leer las cookies implantadas en el disco duro del usuario desde otros servidores.<\/p><p>Podr\u00e1 libremente decidir sobre la implantaci\u00f3n o no en su disco duro de las cookies utilizadas en <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a>. En este sentido, el usuario puede configurar su navegador para aceptar o rechazar por defecto todas las cookies o para recibir un aviso en pantalla de la recepci\u00f3n de cada cookie y decidir en ese momento su implantaci\u00f3n o no en su disco duro. Por eso le sugerimos consultar la secci\u00f3n de ayuda de su navegador para saber c\u00f3mo cambiar la configuraci\u00f3n que actualmente utiliza.<\/p><p>Aunque configura el navegador para rechazar todas las cookies o rechaza expresamente las cookies de <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a>, podr\u00e1 navegar por el Portal con el \u00fanico inconveniente de no poder disfrutar de las funcionalidades del Portal que requieran la instalaci\u00f3n de alguna de ellas. En cualquier caso, podr\u00e1 eliminar las cookies implantadas en su disco duro en cualquier momento, siguiendo el procedimiento establecido en la secci\u00f3n de ayuda de su navegador y que posteriormente detallaremos.<\/p><p>Como usuario, puede rechazar el tratamiento de los datos o la informaci\u00f3n bloqueando estas cookies mediante la configuraci\u00f3n apropiada de su navegador. Sin embargo, debe saber que, si lo hace, este sitio puede no funcionar adecuadamente.<\/p><p>Las cookies de esta web ayudan a:<\/p><ul><li>Hacer que esta web funcione correctamente.<\/li><li>Permitirle visualizar v\u00eddeos.<\/li><li>Mejorar la velocidad \/ seguridad del sitio.<\/li><li>Que pueda compartir p\u00e1ginas con redes sociales.<\/li><li>Mejorar continuamente este sitio web.<\/li><li>Mostrar anuncios en funci\u00f3n de sus h\u00e1bitos de navegaci\u00f3n.<\/li><\/ul><p>Nunca utilizaremos cookies para:<\/p><ul><li>Recoger informaci\u00f3n de identificaci\u00f3n personal (sin su permiso expreso).<\/li><li>Recoger informaci\u00f3n delicada (sin su permiso expreso).<\/li><li>Compartir datos de identificaci\u00f3n personal a terceros.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf74e6d elementor-widget elementor-widget-heading\" data-id=\"cf74e6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">2. Cookies de terceros que utilizamos en esta web y que debe conocer<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adcdec9 elementor-widget elementor-widget-text-editor\" data-id=\"adcdec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta web incluye funcionalidades proporcionadas por terceros.<\/p>\n<p>Tambi\u00e9n se ponen a prueba regularmente nuevos dise\u00f1os o servicios de terceros para recomendaciones e informes.<\/p>\n<p>Esto puede modificar ocasionalmente la configuraci\u00f3n de cookies y que aparezcan cookies no detalladas en la presente pol\u00edtica. Es importante que sepa que son cookies provisionales que no siempre es posible informar y que s\u00f3lo tienen fines de estudio y valoraci\u00f3n. En ning\u00fan caso se utilizar\u00e1n cookies que comprometan su privacidad.<\/p>\n<p>Entre las cookies de terceros m\u00e1s estables est\u00e1n:<\/p>\n<p>Las generadas por servicios de an\u00e1lisis, concretamente, Google Analytics y Google Search Console, para ayudar al sitio web a analizar el uso que hacen los usuarios del sitio web y mejorar su usabilidad, pero en ning\u00fan caso se asocian a datos que podr\u00edan identificar al usuario.<\/p>\n<p>Google Analytics y Google Search Console son servicios de anal\u00edtica web prestados por Google, Inc., una compa\u00f1\u00eda de Delaware cuya sede principal se encuentra en 1600 Amphitheatre Parkway, Mountain View (California), CA 94043, Estados Unidos (\u201cGoogle\u201d).<\/p>\n<p>El usuario puede consultar aqu\u00ed el tipo de cookies utilizadas por Google, seg\u00fan lo dispuesto en su p\u00e1gina sobre qu\u00e9 tipo de cookies utilizan.<\/p>\n<p>WordPress: <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a> es usuaria de la plataforma de suministro y alojamiento de blogs WordPress, propiedad de la empresa estadounidense Automattic, Inc. A estos efectos, el uso de estas cookies por los sistemas nunca est\u00e1 bajo control o gesti\u00f3n del responsable de la web, pueden cambiar su funci\u00f3n en cualquier momento, y entrar cookies nuevas.<\/p>\n<p>Estas cookies tampoco reportan al responsable de esta web ning\u00fan beneficio. Automattic, Inc., utiliza adem\u00e1s otras cookies con el fin de ayudar a identificar y rastrear a los visitantes de los sitios de WordPress, conocer el uso que hacen del sitio web de Automattic, as\u00ed como sus preferencias de acceso al mismo , tal y como se recoge en el apartado \u201cCookies\u201d de su pol\u00edtica de privacidad.<\/p>\n<p>Cookies de redes sociales: Las cookies de redes sociales se pueden almacenar en su navegador mientras navega por <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a>, por ejemplo, cuando haga clic en un enlace de <a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com\/<\/a> que le redirige a alguna red social.<\/p>\n<p>Las empresas que generan estas cookies correspondientes a las redes sociales que utiliza esta web tienen sus propias pol\u00edticas de cookies:<\/p>\n<ul>\n<li>Pol\u00edtica de Cookies de Meta (Matriz de Instagram): <a href=\"https:\/\/privacycenter.instagram.com\/policies\/cookies\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/privacycenter.instagram.com\/policies\/cookies\/<\/a><\/li>\n<\/ul>\n<p>Las implicaciones de privacidad depender\u00e1n de cada red social y dependiendo de la configuraci\u00f3n de privacidad que haya elegido en estas redes. En ning\u00fan caso, ni el responsable de esta web ni los anunciantes pueden obtener informaci\u00f3n personal identificable de estas cookies.<\/p>\n<p>A continuaci\u00f3n, y seg\u00fan exige el art\u00edculo 22.2 de la LSSI-CE, se detallan las cookies que pueden instalarse habitualmente durante la navegaci\u00f3n por este sitio web:<\/p>\n<p>Cookies necesarias:<\/p>\n<ul>\n<li>Terceros: cookieyes-consent. Finalidad: CookieYes configura esta cookie para recordar las preferencias de consentimiento de los usuarios para que sus preferencias se respeten en visitas posteriores a este sitio. No recopila ni almacena ninguna informaci\u00f3n personal sobre los visitantes del sitio. Duraci\u00f3n: 1 a\u00f1o.<\/li>\n<\/ul>\n<p>Cookies anal\u00edticas:<\/p>\n<ul>\n<li>Terceros: <em>ga<\/em>*. Finalidad: Google Analytics configura esta cookie para almacenar y contar las visitas a la p\u00e1gina. Duraci\u00f3n: 1 a\u00f1o, 1 mes y 4 dias.<\/li>\n<li>Terceros: _ga. Finalidad: Google Analytics configura esta cookie para calcular los datos de visitantes, sesiones y campa\u00f1as y realizar un seguimiento del uso del sitio para el informe anal\u00edtico del sitio. La cookie almacena informaci\u00f3n de forma an\u00f3nima y asigna un n\u00famero generado aleatoriamente para reconocer visitantes \u00fanicos. Duraci\u00f3n: 1 a\u00f1o, 1 mes y 4 dias.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bec5a4 elementor-widget elementor-widget-heading\" data-id=\"3bec5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">3. \u00bfC\u00f3mo puedes gestionar y desactivar estas cookies?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c7139 elementor-widget elementor-widget-text-editor\" data-id=\"e4c7139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si prefieres que el sitio web no instale ninguna cookie en tu dispositivo, puedes configurar tu navegador para recibir una notificaci\u00f3n antes de que se descargue cualquier cookie.<\/p><p>Es posible ajustar la configuraci\u00f3n del navegador para desechar todas las cookies o exclusivamente las cookies de terceros. Tambi\u00e9n puedes eliminar cualquiera de las cookies que ya se encuentren en tu equipo. Ten en cuenta que tendr\u00e1s que adaptar por separado la configuraci\u00f3n de cada navegador y equipo que utilices.<\/p><p><a href=\"https:\/\/domingopintor.com\/es\/\" target=\"_new\" rel=\"noreferrer\">https:\/\/domingopintor.com<\/a> pone a disposici\u00f3n de los usuarios que quieran impedir la instalaci\u00f3n de dichas cookies, enlaces proporcionados por los navegadores de uso m\u00e1s extendido por aquellos que deseen evitar la instalaci\u00f3n de estas cookies:<br \/><br \/><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es-419&amp;answer=95647\"><u>Google Chrome<\/u><\/a> \u2013\u00a0<a href=\"https:\/\/support.microsoft.com\/es-es\/windows\/eliminar-y-administrar-cookies-168dab11-0753-043d-7c16-ede5947fc64d\"><u>Internet Explorer<\/u><\/a> \u2013\u00a0<a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\"><u>Mozilla Firefox<\/u><\/a> \u2013\u00a0<a href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_EShttp:\/\/support.apple.com\/kb\/ph5042\"><u>Apple Safari<\/u><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b9efa4 elementor-widget elementor-widget-text-editor\" data-id=\"6b9efa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00daltima modificaci\u00f3n: 2 de agosto de 2024.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Cookies \u00daltima modificaci\u00f3: 2 d&#8217;agost de 2024. Despr\u00e9s d&#8217;una auditoria realitzada per la informaci\u00f3 sobre les cookies que es fan servir en aquest web, us informem: La Llei 34\/2002, d&#8217;11 de juliol, de serveis de la societat de la informaci\u00f3 i de comer\u00e7 electr\u00f2nic (LSSI-CE), obliga a tots aquells que tenen un blog &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/domingopintor.com\/es\/politicadecookies\/\"> <span class=\"screen-reader-text\">Pol\u00edtica de Cookies<\/span> Leer m\u00e1s &raquo;<\/a><\/p>","protected":false},"author":1,"featured_media":993,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2247","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pintors al Maresme, Barcelona i voltants | Domingo Pintors<\/title>\n<meta name=\"description\" content=\"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pintors al Maresme, Barcelona i voltants | Domingo Pintors\" \/>\n<meta property=\"og:description\" content=\"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/domingopintor.com\/es\/politicadecookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Domingo Pintors\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T21:59:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/domingopintor.com\/wp-content\/uploads\/2023\/12\/Untitled-design-60-e1703431132469.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/\",\"url\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/\",\"name\":\"Pintors al Maresme, Barcelona i voltants | Domingo Pintors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/domingopintor.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Untitled-design-60-e1703431132469.png\",\"datePublished\":\"2024-08-02T11:06:11+00:00\",\"dateModified\":\"2024-08-02T21:59:48+00:00\",\"description\":\"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/domingopintor.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Untitled-design-60-e1703431132469.png\",\"contentUrl\":\"https:\\\/\\\/domingopintor.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Untitled-design-60-e1703431132469.png\",\"width\":1280,\"height\":518},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/politicadecookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/domingopintor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#website\",\"url\":\"https:\\\/\\\/domingopintor.com\\\/\",\"name\":\"Domingo Pintors\",\"description\":\"Pintors des de 1903\",\"publisher\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/domingopintor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#organization\",\"name\":\"Domingo Pintors\",\"url\":\"https:\\\/\\\/domingopintor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/domingopintor.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-image-removebg-preview-7.png\",\"contentUrl\":\"https:\\\/\\\/domingopintor.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-image-removebg-preview-7.png\",\"width\":632,\"height\":210,\"caption\":\"Domingo Pintors\"},\"image\":{\"@id\":\"https:\\\/\\\/domingopintor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pintors al Maresme, Barcelona i voltants | Domingo Pintors","description":"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Pintors al Maresme, Barcelona i voltants | Domingo Pintors","og_description":"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.","og_url":"https:\/\/domingopintor.com\/es\/politicadecookies\/","og_site_name":"Domingo Pintors","article_modified_time":"2024-08-02T21:59:48+00:00","og_image":[{"width":1280,"height":518,"url":"http:\/\/domingopintor.com\/wp-content\/uploads\/2023\/12\/Untitled-design-60-e1703431132469.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/domingopintor.com\/politicadecookies\/","url":"https:\/\/domingopintor.com\/politicadecookies\/","name":"Pintors al Maresme, Barcelona i voltants | Domingo Pintors","isPartOf":{"@id":"https:\/\/domingopintor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/domingopintor.com\/politicadecookies\/#primaryimage"},"image":{"@id":"https:\/\/domingopintor.com\/politicadecookies\/#primaryimage"},"thumbnailUrl":"https:\/\/domingopintor.com\/wp-content\/uploads\/2023\/12\/Untitled-design-60-e1703431132469.png","datePublished":"2024-08-02T11:06:11+00:00","dateModified":"2024-08-02T21:59:48+00:00","description":"Amb una \u00e0mplia experi\u00e8ncia al camp de la pintura residencial i comercial, oferim des de renovacions interiors fins a acabats exteriors.","breadcrumb":{"@id":"https:\/\/domingopintor.com\/politicadecookies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/domingopintor.com\/politicadecookies\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/domingopintor.com\/politicadecookies\/#primaryimage","url":"https:\/\/domingopintor.com\/wp-content\/uploads\/2023\/12\/Untitled-design-60-e1703431132469.png","contentUrl":"https:\/\/domingopintor.com\/wp-content\/uploads\/2023\/12\/Untitled-design-60-e1703431132469.png","width":1280,"height":518},{"@type":"BreadcrumbList","@id":"https:\/\/domingopintor.com\/politicadecookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/domingopintor.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/domingopintor.com\/#website","url":"https:\/\/domingopintor.com\/","name":"Domingo Pintors","description":"Pintores des de 1903","publisher":{"@id":"https:\/\/domingopintor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/domingopintor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/domingopintor.com\/#organization","name":"Domingo Pintors","url":"https:\/\/domingopintor.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/domingopintor.com\/#\/schema\/logo\/image\/","url":"https:\/\/domingopintor.com\/wp-content\/uploads\/2024\/04\/cropped-image-removebg-preview-7.png","contentUrl":"https:\/\/domingopintor.com\/wp-content\/uploads\/2024\/04\/cropped-image-removebg-preview-7.png","width":632,"height":210,"caption":"Domingo Pintors"},"image":{"@id":"https:\/\/domingopintor.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/pages\/2247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/comments?post=2247"}],"version-history":[{"count":13,"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/pages\/2247\/revisions"}],"predecessor-version":[{"id":2301,"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/pages\/2247\/revisions\/2301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/media\/993"}],"wp:attachment":[{"href":"https:\/\/domingopintor.com\/es\/wp-json\/wp\/v2\/media?parent=2247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}